{"id":9435,"date":"2026-03-23T15:11:46","date_gmt":"2026-03-23T14:11:46","guid":{"rendered":"https:\/\/fr.lequipenews.ma\/?p=9435"},"modified":"2026-03-23T15:11:47","modified_gmt":"2026-03-23T14:11:47","slug":"dans-lesprit-du-malhoun-la-star-de-x-factor-chaimaa-omran-devoile-son-nouveau-titre-ayit-nkaber","status":"publish","type":"post","link":"https:\/\/fr.lequipenews.ma\/fr\/dans-lesprit-du-malhoun-la-star-de-x-factor-chaimaa-omran-devoile-son-nouveau-titre-ayit-nkaber\/","title":{"rendered":"Dans l\u2019esprit du malhoun\u2026 la star de \u00ab\u202fX Factor\u202f\u00bb, Chaimaa Omran, d\u00e9voile son nouveau titre \u00ab\u202fAyit Nkaber\u202f\u00bb."},"content":{"rendered":"<p><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">l\u2019\u00e9quipe news <\/mark><\/strong><\/p>\n\n\n\n<p>Avec l\u2019esprit du malhoun\u2026 la star de \u00ab\u202fX Factor\u202f\u00bb, Chaimaa Omran, d\u00e9voile son nouveau titre \u00ab\u202fAyit Nkaber\u202f\u00bb<\/p>\n\n\n\n<p>La star de \u00ab\u202fX Factor\u202f\u00bb, Chaimaa Omran, propose une vision artistique m\u00ealant le malhoun \u00e0 la musique contemporaine<\/p>\n\n\n\n<p>Chaimaa Omran pr\u00e9sente un nouvel opus qui allie patrimoine et modernit\u00e9 dans \u00ab\u202fAyit Nkaber\u202f\u00bb<\/p>\n\n\n\n<p>L\u2019artiste Chaimaa Omran revient aupr\u00e8s de son public avec un nouveau morceau intitul\u00e9 \u00ab\u202fAyit Nkaber\u202f\u00bb, une d\u00e9marche artistique qui refl\u00e8te sa vision renouvel\u00e9e et son ambition de cr\u00e9er un \u00e9quilibre unique entre l\u2019authenticit\u00e9 du patrimoine marocain et l\u2019esprit de la musique moderne.<\/p>\n\n\n\n<p>Cette sortie n\u2019est pas une simple chanson passag\u00e8re, mais un projet artistique complet visant \u00e0 redonner ses lettres de noblesse au po\u00e8me traditionnel du malhoun, en le pr\u00e9sentant dans un style contemporain adapt\u00e9 aux attentes de la nouvelle g\u00e9n\u00e9ration, tout en conservant sa profondeur culturelle et la beaut\u00e9 de sa po\u00e9sie.<\/p>\n\n\n\n<p>Pour ce projet, Chaimaa Omran a collabor\u00e9 avec une \u00e9quipe de cr\u00e9ateurs de renom : les paroles ont \u00e9t\u00e9 \u00e9crites par Mohamed El Maghribi, les m\u00e9lodies compos\u00e9es par Mehdi Mzine dans leur premi\u00e8re collaboration, tandis que Madara s\u2019est occup\u00e9 de l\u2019arrangement musical. L\u2019artiste a choisi de produire elle-m\u00eame l\u2019\u0153uvre, d\u00e9montrant ainsi sa maturit\u00e9 artistique et l\u2019ind\u00e9pendance de ses choix.<\/p>\n\n\n\n<p>Dans une d\u00e9claration, Chaimaa Omran a expliqu\u00e9 :<\/p>\n\n\n\n<p>\u00ab\u202f\u00c0 travers \u2018Ayit Nkaber\u2019, je cherche \u00e0 offrir une formule artistique qui allie l\u2019authenticit\u00e9 du malhoun et la modernit\u00e9 de la musique contemporaine, afin que notre patrimoine atteigne la nouvelle g\u00e9n\u00e9ration d\u2019une mani\u00e8re qui respecte leur go\u00fbt et accompagne leurs aspirations.\u202f\u00bb<\/p>\n\n\n\n<p>Avec ce projet, Chaimaa Omran continue de consolider sa place parmi les voix jeunes les plus remarquables de la sc\u00e8ne artistique marocaine, en suivant une approche cr\u00e9ative bas\u00e9e sur l\u2019innovation et la fiert\u00e9 de l\u2019identit\u00e9 nationale, dans une harmonie raffin\u00e9e entre pass\u00e9 et pr\u00e9sent.<\/p>\n\n\n\n<p>Lien YouTube : <a href=\"https:\/\/www.youtube.com\/watch?v=otw_yDzMn7M\" target=\"_blank\" rel=\"noopener\">Chaimaa Omran \u2013 Ayit Nkaber<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>l\u2019\u00e9quipe news Avec l\u2019esprit du malhoun\u2026 la star de \u00ab\u202fX Factor\u202f\u00bb, Chaimaa Omran, d\u00e9voile son nouveau titre \u00ab\u202fAyit Nkaber\u202f\u00bb La star de \u00ab\u202fX Factor\u202f\u00bb, Chaimaa Omran, propose une vision artistique m\u00ealant le malhoun \u00e0 la musique contemporaine Chaimaa Omran pr\u00e9sente un nouvel opus qui allie patrimoine et modernit\u00e9 dans \u00ab\u202fAyit Nkaber\u202f\u00bb L\u2019artiste Chaimaa Omran revient<\/p>","protected":false},"author":1,"featured_media":9436,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[10],"tags":[],"class_list":{"0":"post-9435","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-culture"},"_links":{"self":[{"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/posts\/9435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/comments?post=9435"}],"version-history":[{"count":1,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/posts\/9435\/revisions"}],"predecessor-version":[{"id":9437,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/posts\/9435\/revisions\/9437"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/media\/9436"}],"wp:attachment":[{"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/media?parent=9435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/categories?post=9435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/tags?post=9435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}