{"id":8612,"date":"2026-01-28T17:30:04","date_gmt":"2026-01-28T16:30:04","guid":{"rendered":"https:\/\/fr.lequipenews.ma\/?p=8612"},"modified":"2026-01-28T17:30:05","modified_gmt":"2026-01-28T16:30:05","slug":"lissue-de-laudience-la-decision-finale-concernant-le-match-de-coupe-dafrique-des-nations-entre-le-maroc-et-le-senegal-sera-prise-dans-les-48-heures","status":"publish","type":"post","link":"https:\/\/fr.lequipenews.ma\/fr\/lissue-de-laudience-la-decision-finale-concernant-le-match-de-coupe-dafrique-des-nations-entre-le-maroc-et-le-senegal-sera-prise-dans-les-48-heures\/","title":{"rendered":"l&#8217;issue de l&#8217;audience, la d\u00e9cision finale concernant le match de Coupe d&#8217;Afrique des Nations entre le Maroc et le S\u00e9n\u00e9gal sera prise dans les 48 heures."},"content":{"rendered":"<p><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">L&#8217;\u00c9quipe News\u00a0<\/mark><\/strong><\/p>\n\n\n\n<p>La F\u00e9d\u00e9ration s\u00e9n\u00e9galaise de football a annonc\u00e9 que la Conf\u00e9d\u00e9ration africaine de football rendra sa d\u00e9cision finale concernant le match final de la Coupe d&#8217;Afrique des Nations entre les \u00e9quipes nationales marocaine et s\u00e9n\u00e9galaise dans un d\u00e9lai maximum de 48 heures.<\/p>\n\n\n\n<p>La F\u00e9d\u00e9ration s\u00e9n\u00e9galaise a expliqu\u00e9 dans un communiqu\u00e9 officiel que son secr\u00e9taire g\u00e9n\u00e9ral avait assist\u00e9, le mardi 27 janvier, \u00e0 l&#8217;audience tenue par la Commission de discipline de la CAF, accompagn\u00e9 de l&#8217;entra\u00eeneur Pape Bouna Thiaw et de deux joueurs de l&#8217;\u00e9quipe nationale, afin de fournir leurs explications concernant les \u00e9v\u00e9nements qui se sont d\u00e9roul\u00e9s lors de la finale continentale.<\/p>\n\n\n\n<p>Le communiqu\u00e9 indiquait que cette s\u00e9ance faisait suite aux rapports soumis par les officiels du match, ainsi qu&#8217;aux r\u00e9serves formul\u00e9es par la F\u00e9d\u00e9ration marocaine de football apr\u00e8s la finale de la Coupe d&#8217;Afrique des Nations Maroc 2025.<\/p>\n\n\n\n<p>La F\u00e9d\u00e9ration s\u00e9n\u00e9galaise de football a confirm\u00e9 avoir remis un m\u00e9moire juridique complet, pr\u00e9par\u00e9 par son avocat Seydou Diagne, contenant une r\u00e9ponse d\u00e9taill\u00e9e \u00e0 tous les points soulev\u00e9s dans cette affaire. Les d\u00e9clarations de l&#8217;entra\u00eeneur Pape Bouna Thiaw et des joueurs Ismaila Sarr et Elman Ndiaye ont \u00e9galement \u00e9t\u00e9 entendues, lors de la pr\u00e9sentation de leur d\u00e9fense devant l&#8217;instance disciplinaire.<\/p>\n\n\n\n<p>La F\u00e9d\u00e9ration s\u00e9n\u00e9galaise de football a conclu son communiqu\u00e9 en confirmant que la commission de discipline de la Conf\u00e9d\u00e9ration africaine de football poursuit l&#8217;examen du dossier et que les parties concern\u00e9es seront inform\u00e9es de la d\u00e9cision finale dans les 48 heures, conform\u00e9ment au d\u00e9lai fix\u00e9 par le pr\u00e9sident de l&#8217;instance disciplinaire.<\/p>","protected":false},"excerpt":{"rendered":"<p>L&#8217;\u00c9quipe News\u00a0 La F\u00e9d\u00e9ration s\u00e9n\u00e9galaise de football a annonc\u00e9 que la Conf\u00e9d\u00e9ration africaine de football rendra sa d\u00e9cision finale concernant le match final de la Coupe d&#8217;Afrique des Nations entre les \u00e9quipes nationales marocaine et s\u00e9n\u00e9galaise dans un d\u00e9lai maximum de 48 heures. La F\u00e9d\u00e9ration s\u00e9n\u00e9galaise a expliqu\u00e9 dans un communiqu\u00e9 officiel que son secr\u00e9taire<\/p>","protected":false},"author":1,"featured_media":8613,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-8612","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-sport"},"_links":{"self":[{"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/posts\/8612","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/comments?post=8612"}],"version-history":[{"count":1,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/posts\/8612\/revisions"}],"predecessor-version":[{"id":8614,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/posts\/8612\/revisions\/8614"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/media\/8613"}],"wp:attachment":[{"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/media?parent=8612"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/categories?post=8612"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/tags?post=8612"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}