{"id":8202,"date":"2025-12-23T19:59:53","date_gmt":"2025-12-23T18:59:53","guid":{"rendered":"https:\/\/fr.lequipenews.ma\/?p=8202"},"modified":"2025-12-23T19:59:54","modified_gmt":"2025-12-23T18:59:54","slug":"des-stades-aux-ecrans-la-fifa-annonce-la-coupe-du-monde-des-clubs-de-la-fifa-eworldcoupe","status":"publish","type":"post","link":"https:\/\/fr.lequipenews.ma\/fr\/des-stades-aux-ecrans-la-fifa-annonce-la-coupe-du-monde-des-clubs-de-la-fifa-eworldcoupe\/","title":{"rendered":"Des stades aux \u00e9crans : la FIFA annonce la Coupe du Monde des Clubs de la FIFA eWorldCoupe"},"content":{"rendered":"<p><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">L&#8217;\u00c9quipe News<\/mark><\/strong><\/p>\n\n\n\n<p>La FIFA et Sports Interactive ont annonc\u00e9 le lancement d&#8217;une nouvelle comp\u00e9tition appel\u00e9e FIFAe Club World Cup, qui rejoindra les comp\u00e9titions eSports du jeu Football Manager \u00e0 partir de 2026. Il s&#8217;agira du premier tournoi du genre d\u00e9di\u00e9 aux clubs dans les comp\u00e9titions de Football Manager, rapprochant ainsi l&#8217;exp\u00e9rience num\u00e9rique des fans de football du monde entier.<\/p>\n\n\n\n<p>Cette comp\u00e9tition r\u00e9unira des clubs du monde entier, dont les joueurs s&#8217;affronteront pour repr\u00e9senter leurs \u00e9quipes dans un environnement num\u00e9rique ax\u00e9 sur les comp\u00e9tences tactiques, la gestion d&#8217;\u00e9quipe et la construction d&#8217;un effectif \u00e0 long terme. Le lancement de ce tournoi fait suite au succ\u00e8s de la premi\u00e8re \u00e9dition de Football Manager organis\u00e9e par Liverpool en 2024.<\/p>\n\n\n\n<p>Un syst\u00e8me de qualification \u00e9largi en 2026 permettra aux clubs de d\u00e9signer leurs repr\u00e9sentants officiels pour participer, dans un cadre qui allie la passion du football \u00e0 une expertise strat\u00e9gique dans l&#8217;esport.<\/p>\n\n\n\n<p>La FIFA a invit\u00e9 les clubs du monde entier \u00e0 s&#8217;inscrire \u00e0 la comp\u00e9tition via FIFA.GG, et de plus amples informations seront d\u00e9voil\u00e9es d\u00e9but 2026. Ce tournoi constituera un \u00e9l\u00e9ment cl\u00e9 de l&#8217;\u00e9cosyst\u00e8me e-sport en pleine expansion de FIFAe.<\/p>","protected":false},"excerpt":{"rendered":"<p>L&#8217;\u00c9quipe News La FIFA et Sports Interactive ont annonc\u00e9 le lancement d&#8217;une nouvelle comp\u00e9tition appel\u00e9e FIFAe Club World Cup, qui rejoindra les comp\u00e9titions eSports du jeu Football Manager \u00e0 partir de 2026. Il s&#8217;agira du premier tournoi du genre d\u00e9di\u00e9 aux clubs dans les comp\u00e9titions de Football Manager, rapprochant ainsi l&#8217;exp\u00e9rience num\u00e9rique des fans de<\/p>","protected":false},"author":1,"featured_media":8203,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-8202","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-sport"},"_links":{"self":[{"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/posts\/8202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/comments?post=8202"}],"version-history":[{"count":1,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/posts\/8202\/revisions"}],"predecessor-version":[{"id":8204,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/posts\/8202\/revisions\/8204"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/media\/8203"}],"wp:attachment":[{"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/media?parent=8202"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/categories?post=8202"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/tags?post=8202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}