{"id":7832,"date":"2025-11-09T17:41:09","date_gmt":"2025-11-09T16:41:09","guid":{"rendered":"https:\/\/fr.lequipenews.ma\/?p=7832"},"modified":"2025-11-09T17:41:10","modified_gmt":"2025-11-09T16:41:10","slug":"lequipe-reserve-de-lequipe-nationale-marocaine-entre-en-stage-dentrainement-en-vue-de-la-coupe-arabe-au-qatar","status":"publish","type":"post","link":"https:\/\/fr.lequipenews.ma\/fr\/lequipe-reserve-de-lequipe-nationale-marocaine-entre-en-stage-dentrainement-en-vue-de-la-coupe-arabe-au-qatar\/","title":{"rendered":"L&#8217;\u00e9quipe r\u00e9serve de l&#8217;\u00e9quipe nationale marocaine entre en stage d&#8217;entra\u00eenement en vue de la Coupe arabe au Qatar."},"content":{"rendered":"<p><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">L&#8217;\u00c9quipe News\u00a0<\/mark><\/strong><\/p>\n\n\n\n<p>Tariq Sektioui, l&#8217;entra\u00eeneur de l&#8217;\u00e9quipe nationale r\u00e9serve, a annonc\u00e9 une liste de 29 joueurs qui participeront \u00e0 un stage de pr\u00e9paration \u00e0 huis clos au complexe de football Mohammed VI, du 10 au 18 novembre 2025, en vue de leur participation \u00e0 la Coupe arabe, qui se d\u00e9roulera au Qatar du 1er au 18 d\u00e9cembre.<\/p>\n\n\n\n<p>Ce stage vise \u00e0 \u00e9valuer le niveau des joueurs et \u00e0 instaurer l&#8217;harmonie n\u00e9cessaire entre eux avant le d\u00e9but de la comp\u00e9tition, d&#8217;autant plus que l&#8217;\u00e9quipe r\u00e9serve marocaine devra relever de s\u00e9rieux d\u00e9fis dans le groupe B, qui comprend l&#8217;Arabie saoudite, le vainqueur du match entre Oman et la Somalie, et le vainqueur du match entre le Y\u00e9men et les Comores.<\/p>\n\n\n\n<p>Liste des joueurs participants&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Gardiens : Salah Eddine Chehab (Maghreb F\u00e8s), Mehdi Benabid (Wydad Casablanca), Rachid Ghanimi (Fath Rabat).<\/li>\n\n\n\n<li>D\u00e9fenseurs : Haitham Manout, Hamza Moussaoui (Renaissance Berkane), Marouane El Ouadni, Younes Abdelhamid, Anas Bach (FAR Rabat), Mohamed Boulksout (Raja Casablanca), Mohamed Moufid (Wydad Casablanca), Marouane Saadane (Al-Fateh Saudi), Soufiane Bouftini (Al-Wasl UAE), Mahmoud Bentayk (Zamalek Egypt).<\/li>\n\n\n\n<li>Milieu de terrain : Ayoub Khairi (Renaissance Berkane), Khalid Ait Ourkhan, Mohamed Rabie Harimat (FAR Rabat), Saber Bougrine (Raja Casablanca), Achraf El Mahdaoui (Al Taawon Saudi), Walid El Karti (Pyramids FC).<\/li>\n\n\n\n<li>Attaquants : Youssef Mehri, Mounir Chouiar (RS Berkane), Hamza El Hanouri (Wydad Casablanca), Abderrazak Hamdallah (Al Shabab Saudi), Karim El Berkaoui (Al Dhafra EAU), Walid Azaro (Ajman EAU), Tarik Tissoudali (Khorfakkan EAU), Oussama Tannane (Umm Salal Qatar), Amine Zahzouh (Al Wakrah). Qatar), Achraf Bencharki (Al Ahly Egypte)<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>L&#8217;\u00c9quipe News\u00a0 Tariq Sektioui, l&#8217;entra\u00eeneur de l&#8217;\u00e9quipe nationale r\u00e9serve, a annonc\u00e9 une liste de 29 joueurs qui participeront \u00e0 un stage de pr\u00e9paration \u00e0 huis clos au complexe de football Mohammed VI, du 10 au 18 novembre 2025, en vue de leur participation \u00e0 la Coupe arabe, qui se d\u00e9roulera au Qatar du 1er au<\/p>","protected":false},"author":1,"featured_media":7833,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-7832","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-sport"},"_links":{"self":[{"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/posts\/7832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/comments?post=7832"}],"version-history":[{"count":1,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/posts\/7832\/revisions"}],"predecessor-version":[{"id":7834,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/posts\/7832\/revisions\/7834"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/media\/7833"}],"wp:attachment":[{"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/media?parent=7832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/categories?post=7832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/tags?post=7832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}