{"id":7754,"date":"2025-11-05T22:06:01","date_gmt":"2025-11-05T21:06:01","guid":{"rendered":"https:\/\/fr.lequipenews.ma\/?p=7754"},"modified":"2025-11-05T22:08:38","modified_gmt":"2025-11-05T21:08:38","slug":"lequipe-news-felicite-sa-majeste-le-roi-mohammed-vi-a-loccasion-du-50e-anniversaire-de-la-marche-verte","status":"publish","type":"post","link":"https:\/\/fr.lequipenews.ma\/fr\/lequipe-news-felicite-sa-majeste-le-roi-mohammed-vi-a-loccasion-du-50e-anniversaire-de-la-marche-verte\/","title":{"rendered":"L&#8217;\u00c9quipe News f\u00e9licite Sa Majest\u00e9 le Roi Mohammed VI \u00e0 l&#8217;occasion du 50e anniversaire de la Marche Verte."},"content":{"rendered":"<p><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">L&#8217;\u00c9quipe News\u00a0<\/mark><\/strong><\/p>\n\n\n\n<p><strong>Par Abdel Fattah Takheem&nbsp;<\/strong><\/p>\n\n\n\n<p>Monsieur Abdel Fattah Tekhim, directeur de la publication de L\u2019\u00c9quipe News, a l\u2019honneur, en son nom propre et au nom de l\u2019ensemble du personnel du journal, d\u2019adresser \u00e0 Sa Majest\u00e9 le Roi Mohammed VI, que Dieu lui accorde victoire et soutien, ses plus hautes f\u00e9licitations et ses plus sinc\u00e8res v\u0153ux, \u00e0 l\u2019occasion de la comm\u00e9moration par le peuple marocain du cinquanti\u00e8me anniversaire de la Marche Verte triomphante.<\/p>\n\n\n\n<p>En cette pr\u00e9cieuse f\u00eate nationale, M. Abdel Fattah Takhim prie le Tout-Puissant d&#8217;accorder \u00e0 Sa Majest\u00e9 une sant\u00e9, un bien-\u00eatre et une longue vie, de le b\u00e9nir en lui donnant la b\u00e9n\u00e9diction de son cher prince h\u00e9ritier, Son Altesse Royale le prince Moulay Hassan, et de le fortifier aupr\u00e8s de son fr\u00e8re, Son Altesse Royale le prince Moulay Rachid. Il prie \u00e9galement de prot\u00e9ger tous les membres de la noble famille royale et de perp\u00e9tuer les bienfaits de la s\u00e9curit\u00e9, de la stabilit\u00e9 et de la prosp\u00e9rit\u00e9 sur notre ch\u00e8re patrie. Il est Celui qui entend tout, Celui qui exauce les pri\u00e8res.<\/p>\n\n\n\n<p>L\u2019\u00c9quipe News saisit cette pr\u00e9cieuse occasion pour renouveler sa fiert\u00e9 et son honneur pour les gloires immortelles et la ferme unit\u00e9 territoriale obtenues par la Marche Verte, renouvelant son engagement de loyaut\u00e9 et de d\u00e9votion envers la patrie et le glorieux tr\u00f4ne alaouite, et demandant \u00e0 Dieu de prot\u00e9ger le Royaume du Maroc et son noble peuple sous la sage direction de Sa Majest\u00e9.<\/p>\n\n\n\n<p>Serviteur des Saints Sanctuaires.<\/p>\n\n\n\n<p>Directeur de publication &#8211; Abdel Fattah Takheem&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>L&#8217;\u00c9quipe News\u00a0 Par Abdel Fattah Takheem&nbsp; Monsieur Abdel Fattah Tekhim, directeur de la publication de L\u2019\u00c9quipe News, a l\u2019honneur, en son nom propre et au nom de l\u2019ensemble du personnel du journal, d\u2019adresser \u00e0 Sa Majest\u00e9 le Roi Mohammed VI, que Dieu lui accorde victoire et soutien, ses plus hautes f\u00e9licitations et ses plus sinc\u00e8res<\/p>","protected":false},"author":1,"featured_media":7760,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[4],"tags":[],"class_list":{"0":"post-7754","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-activites-royales"},"_links":{"self":[{"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/posts\/7754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/comments?post=7754"}],"version-history":[{"count":1,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/posts\/7754\/revisions"}],"predecessor-version":[{"id":7756,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/posts\/7754\/revisions\/7756"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/media\/7760"}],"wp:attachment":[{"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/media?parent=7754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/categories?post=7754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/tags?post=7754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}