{"id":7121,"date":"2025-09-27T14:06:26","date_gmt":"2025-09-27T13:06:26","guid":{"rendered":"https:\/\/fr.lequipenews.ma\/?p=7121"},"modified":"2025-09-27T14:06:27","modified_gmt":"2025-09-27T13:06:27","slug":"la-vente-des-billets-pour-la-coupe-du-monde-de-futsal-feminin-de-la-fifa-philippines-2025-a-commence","status":"publish","type":"post","link":"https:\/\/fr.lequipenews.ma\/fr\/la-vente-des-billets-pour-la-coupe-du-monde-de-futsal-feminin-de-la-fifa-philippines-2025-a-commence\/","title":{"rendered":"La vente des billets pour la Coupe du Monde de Futsal F\u00e9minin de la FIFA, Philippines 2025\u2122 a commenc\u00e9."},"content":{"rendered":"<p><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">Actualit\u00e9s de L&#8217;\u00c9quipe\u00a0<\/mark><\/strong><\/p>\n\n\n\n<p>La FIFA a annonc\u00e9 le lancement de la vente de billets pour la premi\u00e8re Coupe du Monde F\u00e9minine de Futsal de la FIFA\u2122, qui se tiendra aux Philippines du 21 novembre au 7 d\u00e9cembre 2025.<\/p>\n\n\n\n<p>Les supporters peuvent r\u00e9server leurs billets exclusivement sur le site officiel&nbsp;: FIFA.com\/tickets, \u00e0 partir de 499 pesos philippins (environ 9&nbsp;dollars am\u00e9ricains) par billet, ce qui permet d&#8217;assister \u00e0 deux matchs le m\u00eame jour et au m\u00eame stade. Des billets sp\u00e9ciaux seront \u00e9galement disponibles, permettant aux supporters d&#8217;assister \u00e0 quatre matchs le m\u00eame jour \u00e0 des dates pr\u00e9cises.<\/p>\n\n\n\n<p>Le tournoi verra la participation de 16 \u00e9quipes en comp\u00e9tition pour le premier titre mondial : l&#8217;Argentine, le Br\u00e9sil, le Canada, la Colombie, l&#8217;Iran, l&#8217;Italie, le Japon, le Maroc, la Nouvelle-Z\u00e9lande, le Panama, la Pologne, le Portugal, l&#8217;Espagne, la Tanzanie, la Tha\u00eflande et le pays h\u00f4te, les Philippines.<\/p>\n\n\n\n<p>Tous les matchs auront lieu \u00e0 la PhilSports Arena de Pasig City, Metro Manila, o\u00f9 les fans pourront voir certaines des meilleures joueuses internationales de futsal f\u00e9minin dans ce qui devrait \u00eatre un \u00e9v\u00e9nement sportif historique qui consolidera le statut du football f\u00e9minin sur la sc\u00e8ne mondiale.<\/p>","protected":false},"excerpt":{"rendered":"<p>Actualit\u00e9s de L&#8217;\u00c9quipe\u00a0 La FIFA a annonc\u00e9 le lancement de la vente de billets pour la premi\u00e8re Coupe du Monde F\u00e9minine de Futsal de la FIFA\u2122, qui se tiendra aux Philippines du 21 novembre au 7 d\u00e9cembre 2025. Les supporters peuvent r\u00e9server leurs billets exclusivement sur le site officiel&nbsp;: FIFA.com\/tickets, \u00e0 partir de 499 pesos<\/p>","protected":false},"author":1,"featured_media":7122,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-7121","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-sport"},"_links":{"self":[{"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/posts\/7121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/comments?post=7121"}],"version-history":[{"count":1,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/posts\/7121\/revisions"}],"predecessor-version":[{"id":7123,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/posts\/7121\/revisions\/7123"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/media\/7122"}],"wp:attachment":[{"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/media?parent=7121"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/categories?post=7121"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/tags?post=7121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}