{"id":6278,"date":"2025-07-10T02:00:22","date_gmt":"2025-07-10T01:00:22","guid":{"rendered":"https:\/\/fr.lequipenews.ma\/?p=6278"},"modified":"2025-07-10T02:00:23","modified_gmt":"2025-07-10T01:00:23","slug":"danone-rejoint-officiellement-les-partenaires-de-la-caf-a-loccasion-de-la-coupe-dafrique-des-nations-2025-pour-promouvoir-la-sante-et-la-nutrition-a-travers-le-sport","status":"publish","type":"post","link":"https:\/\/fr.lequipenews.ma\/fr\/danone-rejoint-officiellement-les-partenaires-de-la-caf-a-loccasion-de-la-coupe-dafrique-des-nations-2025-pour-promouvoir-la-sante-et-la-nutrition-a-travers-le-sport\/","title":{"rendered":"Danone rejoint officiellement les partenaires de la CAF \u00e0 l&#8217;occasion de la Coupe d&#8217;Afrique des Nations 2025 pour promouvoir la sant\u00e9 et la nutrition \u00e0 travers le sport"},"content":{"rendered":"<p><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">L\u2019\u00e9quipe news <\/mark><\/strong><\/p>\n\n\n\n<p>La Conf\u00e9d\u00e9ration Africaine de Football (CAF) et Danone, leader mondial de l\u2019alimentation et de la nutrition, ont annonc\u00e9 un partenariat officiel couvrant la Coupe d\u2019Afrique des Nations TotalEnergies (\u00ab CAN \u00bb) Maroc 2025 et la Coupe d\u2019Afrique des Nations F\u00e9minine (\u00ab WAFCON \u00bb) Maroc 2024.<\/p>\n\n\n\n<p>Ce partenariat vise \u00e0 promouvoir la sant\u00e9 par la nutrition, en fournissant des produits laitiers nutritifs \u00e0 plus de 10&nbsp;000 b\u00e9n\u00e9voles et 5&nbsp;000 journalistes accr\u00e9dit\u00e9s, ainsi qu&#8217;aux officiels et aux membres des \u00e9quipes participantes. Danone apportera \u00e9galement son expertise nutritionnelle aux supporters dans les stades et les fan zones officielles, \u00e0 travers six marques de premier plan&nbsp;: Danone, Fanmilk, DanUp, Nutriday, Asiri et Jamila.<\/p>\n\n\n\n<p>Le Dr Patrice Motsepe, pr\u00e9sident de la CAF, a d\u00e9clar\u00e9 :<\/p>\n\n\n\n<p>Nous sommes ravis d&#8217;accueillir Danone parmi nos partenaires officiels. Ce partenariat incarne notre engagement commun \u00e0 soutenir la jeunesse africaine et \u00e0 promouvoir des modes de vie sains sur le continent. Il t\u00e9moigne de la confiance que les grandes entreprises mondiales accordent \u00e0 la CAF, un partenaire efficace pour le d\u00e9veloppement du football en Afrique.<\/p>\n\n\n\n<p>De son c\u00f4t\u00e9, Antoine de Saint-Afrique, PDG de Danone, a d\u00e9clar\u00e9 :<\/p>\n\n\n\n<p>Ce partenariat s&#8217;inscrit parfaitement dans notre mission : promouvoir la sant\u00e9 par l&#8217;alimentation pour le plus grand nombre. Nous sommes fiers de participer \u00e0 ces \u00e9v\u00e9nements embl\u00e9matiques et impatients de contribuer \u00e0 la diffusion d&#8217;une culture de l&#8217;alimentation \u00e9quilibr\u00e9e et de l&#8217;activit\u00e9 physique.<\/p>\n\n\n\n<p>\u00c0 long terme, Danone collaborera avec la CAF dans le cadre du Championnat d\u2019Afrique scolaire, en d\u00e9veloppant des ressources p\u00e9dagogiques \u00e0 destination des \u00e9l\u00e8ves de football des \u00e9coles, dans le but de les sensibiliser \u00e0 l\u2019importance d\u2019une alimentation saine d\u00e8s le plus jeune \u00e2ge.<\/p>\n\n\n\n<p>Ce partenariat repr\u00e9sente un mod\u00e8le exemplaire d\u2019int\u00e9gration entre le sport et la nutrition et incarne la vision commune de Danone et de la CAF pour un continent plus sain, plus actif et plus brillant.<\/p>","protected":false},"excerpt":{"rendered":"<p>L\u2019\u00e9quipe news La Conf\u00e9d\u00e9ration Africaine de Football (CAF) et Danone, leader mondial de l\u2019alimentation et de la nutrition, ont annonc\u00e9 un partenariat officiel couvrant la Coupe d\u2019Afrique des Nations TotalEnergies (\u00ab CAN \u00bb) Maroc 2025 et la Coupe d\u2019Afrique des Nations F\u00e9minine (\u00ab WAFCON \u00bb) Maroc 2024. Ce partenariat vise \u00e0 promouvoir la sant\u00e9 par<\/p>","protected":false},"author":1,"featured_media":6279,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-6278","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-sport"},"_links":{"self":[{"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/posts\/6278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/comments?post=6278"}],"version-history":[{"count":1,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/posts\/6278\/revisions"}],"predecessor-version":[{"id":6280,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/posts\/6278\/revisions\/6280"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/media\/6279"}],"wp:attachment":[{"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/media?parent=6278"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/categories?post=6278"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/tags?post=6278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}