{"id":5760,"date":"2025-05-31T14:24:34","date_gmt":"2025-05-31T13:24:34","guid":{"rendered":"https:\/\/fr.lequipenews.ma\/?p=5760"},"modified":"2025-05-31T14:24:35","modified_gmt":"2025-05-31T13:24:35","slug":"vervault-2025-dix-jours-de-creativite-et-de-spectacle-au-coeur-du-bocage-pour-celebrer-le-tour-de-france","status":"publish","type":"post","link":"https:\/\/fr.lequipenews.ma\/fr\/vervault-2025-dix-jours-de-creativite-et-de-spectacle-au-coeur-du-bocage-pour-celebrer-le-tour-de-france\/","title":{"rendered":"Vervault 2025 : Dix jours de cr\u00e9ativit\u00e9 et de spectacle au c\u0153ur du bocage, pour c\u00e9l\u00e9brer le Tour de France"},"content":{"rendered":"<p><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">Actualit\u00e9s de L&#8217;\u00c9quipe<\/mark><\/strong><\/p>\n\n\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">Suivi &#8211; Abdel Fattah Takhim<\/mark><\/p>\n\n\n\n<p>La ville de Vers-Normandie (Calvados) s&#8217;appr\u00eate \u00e0 accueillir une \u00e9dition sp\u00e9ciale du festival \u00ab Les Virevolt\u00e9s \u00bb, qui se d\u00e9roulera du 1er au 10 juillet 2025. Le bocage se transformera en sc\u00e8ne de street art \u00e0 ciel ouvert, dans un m\u00e9lange unique de cr\u00e9ativit\u00e9 artistique et d&#8217;esprit v\u00e9lo.<\/p>\n\n\n\n<p>Pour sa 34e \u00e9dition, le festival gratuit a d\u00e9cid\u00e9 cette ann\u00e9e de c\u00e9l\u00e9brer \u00e0 sa mani\u00e8re le Tour de France, qui arrivera \u00e0 Vert le 10 juillet. Les organisateurs promettent \u00e0 leurs fans une soir\u00e9e finale exceptionnelle, avec un programme riche en performances qui accompagneront l&#8217;arriv\u00e9e des cyclistes de \u00ab La Grande Bois \u00bb.<\/p>\n\n\n\n<p>Le pr\u00e9sident du festival, Michael Grou, a expliqu\u00e9 que la derni\u00e8re journ\u00e9e sera le point culminant des c\u00e9l\u00e9brations, avec de multiples performances artistiques qui auront lieu dans toute la ville, soulignant que cette programmation est \u00ab con\u00e7ue pour \u00eatre \u00e0 la hauteur de cet \u00e9v\u00e9nement national majeur \u00bb.<\/p>\n\n\n\n<p>L\u2019une des repr\u00e9sentations les plus attendues est \u00ab Bleue Volute \u00bb de la compagnie Minuit, une \u0153uvre artistique magique qui aura lieu \u00e0 la Porte-Horloge \u00e0 20h30. Le spectacle a \u00e9t\u00e9 pr\u00e9sent\u00e9 pour la premi\u00e8re fois le 9 mai et a impressionn\u00e9 le public.<\/p>\n\n\n\n<p>Le festival promet \u00e9galement une vari\u00e9t\u00e9 d&#8217;activit\u00e9s, des funambules et des num\u00e9ros acrobatiques aux DJ mobiles \u00e0 v\u00e9lo, ainsi que des d\u00e9fil\u00e9s excentriques et des spectacles inspir\u00e9s de s\u00e9ries t\u00e9l\u00e9vis\u00e9es populaires, comme ceux pr\u00e9sent\u00e9s par les Peaky Bikers, qui combinent excitation et performance athl\u00e9tique sur des v\u00e9los BMX.<\/p>\n\n\n\n<p>Ainsi, Fair s&#8217;appr\u00eate \u00e0 vivre dix jours de divertissement et de f\u00eate ouverts \u00e0 tous, dans un \u00e9v\u00e9nement qui prouve une fois de plus que la culture est capable d&#8217;accompagner les grands \u00e9v\u00e9nements sportifs, et m\u00eame de leur donner un esprit nouveau et unique.<\/p>","protected":false},"excerpt":{"rendered":"<p>Actualit\u00e9s de L&#8217;\u00c9quipe Suivi &#8211; Abdel Fattah Takhim La ville de Vers-Normandie (Calvados) s&#8217;appr\u00eate \u00e0 accueillir une \u00e9dition sp\u00e9ciale du festival \u00ab Les Virevolt\u00e9s \u00bb, qui se d\u00e9roulera du 1er au 10 juillet 2025. Le bocage se transformera en sc\u00e8ne de street art \u00e0 ciel ouvert, dans un m\u00e9lange unique de cr\u00e9ativit\u00e9 artistique et d&#8217;esprit<\/p>","protected":false},"author":1,"featured_media":5761,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-5760","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-sport"},"_links":{"self":[{"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/posts\/5760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/comments?post=5760"}],"version-history":[{"count":1,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/posts\/5760\/revisions"}],"predecessor-version":[{"id":5762,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/posts\/5760\/revisions\/5762"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/media\/5761"}],"wp:attachment":[{"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/media?parent=5760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/categories?post=5760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/tags?post=5760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}