{"id":5112,"date":"2025-05-08T13:40:40","date_gmt":"2025-05-08T12:40:40","guid":{"rendered":"https:\/\/fr.lequipenews.ma\/?p=5112"},"modified":"2025-05-08T13:40:40","modified_gmt":"2025-05-08T12:40:40","slug":"hakimi-brille-contre-arsenal-menant-le-paris-saint-germain-en-finale-de-la-ligue-des-champions","status":"publish","type":"post","link":"https:\/\/fr.lequipenews.ma\/fr\/hakimi-brille-contre-arsenal-menant-le-paris-saint-germain-en-finale-de-la-ligue-des-champions\/","title":{"rendered":"Hakimi brille contre Arsenal, menant le Paris Saint-Germain en finale de la Ligue des champions"},"content":{"rendered":"<p><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">l\u2019\u00e9quipe news <\/mark><\/strong><\/p>\n\n\n\n<p><strong>Jeudi 8 mai 2025 &#8211; 09:25<\/strong><\/p>\n\n\n\n<p>L&#8217;international marocain Achraf Hakimi a brill\u00e9 lors de la soir\u00e9e o\u00f9 le Paris Saint-Germain a obtenu une qualification historique pour la finale de la Ligue des champions, en battant Arsenal 2-1 au match retour de la demi-finale. La performance impressionnante de Hakimi lui a valu le prix de l&#8217;Homme du match, apr\u00e8s avoir r\u00e9alis\u00e9 une belle performance et marqu\u00e9 le deuxi\u00e8me but de son \u00e9quipe avec une frappe \u00e9poustouflante.<\/p>\n\n\n\n<p>Hakimi a confirm\u00e9 dans ses d\u00e9clarations apr\u00e8s le match :<\/p>\n\n\n\n<p>\u00ab Nous sommes fiers de nous et savons que le chemin n&#8217;a pas \u00e9t\u00e9 facile. Nous avons fr\u00f4l\u00e9 l&#8217;\u00e9limination, mais nous avons cru en nous, en tant que groupe, et aujourd&#8217;hui, nous en r\u00e9coltons les fruits. \u00bb<\/p>\n\n\n\n<p>Il a ajout\u00e9 :<\/p>\n\n\n\n<p>\u00ab Nous remercions nos fid\u00e8les supporters qui nous ont soutenus tout au long de la saison et nous promettons de continuer \u00e0 nous battre pour ramener la coupe \u00e0 la maison. \u00bb<\/p>\n\n\n\n<p>Le Paris Saint-Germain affrontera l&#8217;Inter Milan lors de la finale tr\u00e8s attendue le 31 mai \u00e0 Munich, alors qu&#8217;ils chercheront \u00e0 remporter leur premier titre europ\u00e9en.<\/p>","protected":false},"excerpt":{"rendered":"<p>l\u2019\u00e9quipe news Jeudi 8 mai 2025 &#8211; 09:25 L&#8217;international marocain Achraf Hakimi a brill\u00e9 lors de la soir\u00e9e o\u00f9 le Paris Saint-Germain a obtenu une qualification historique pour la finale de la Ligue des champions, en battant Arsenal 2-1 au match retour de la demi-finale. La performance impressionnante de Hakimi lui a valu le prix<\/p>","protected":false},"author":1,"featured_media":5113,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-5112","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-sport"},"_links":{"self":[{"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/posts\/5112","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/comments?post=5112"}],"version-history":[{"count":1,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/posts\/5112\/revisions"}],"predecessor-version":[{"id":5114,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/posts\/5112\/revisions\/5114"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/media\/5113"}],"wp:attachment":[{"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/media?parent=5112"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/categories?post=5112"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/tags?post=5112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}