{"id":4223,"date":"2025-04-04T13:03:19","date_gmt":"2025-04-04T12:03:19","guid":{"rendered":"https:\/\/fr.lequipenews.ma\/?p=4223"},"modified":"2025-04-04T13:05:47","modified_gmt":"2025-04-04T12:05:47","slug":"4223-2","status":"publish","type":"post","link":"https:\/\/fr.lequipenews.ma\/fr\/4223-2\/","title":{"rendered":"Classement mondial de futsal de la FIFA : d\u00e9but impressionnant de l&#8217;Australie et surprises au classement masculin"},"content":{"rendered":"<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">l\u2019\u00e9quipe news<\/mark><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Vendredi 4 avril 2025 &#8211; 11h50<\/p>\n\n\n\n<p>La FIFA a d\u00e9voil\u00e9 la premi\u00e8re \u00e9dition de son classement mondial de futsal pour 2025, avec plusieurs changements notables dans la liste apr\u00e8s que 183 matchs f\u00e9minins et 192 matchs masculins aient \u00e9t\u00e9 jou\u00e9s.<\/p>\n\n\n\n<p>Futsal f\u00e9minin : l&#8217;Australie entre en force au classement<\/p>\n\n\n\n<p>Le classement du futsal f\u00e9minin a connu une augmentation du nombre de matchs, avec 111 matchs jou\u00e9s jusqu&#8217;\u00e0 pr\u00e9sent, soit le double du nombre par rapport \u00e0 la m\u00eame p\u00e9riode l&#8217;ann\u00e9e derni\u00e8re. Cependant, les quatre premi\u00e8res positions sont rest\u00e9es inchang\u00e9es, le Br\u00e9sil \u00e9tant toujours en t\u00eate, suivi de l&#8217;Espagne, du Portugal et de l&#8217;Argentine.<\/p>\n\n\n\n<p>Le classement a vu des progr\u00e8s significatifs pour un certain nombre d&#8217;\u00e9quipes, notamment :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Maroc (47e, en hausse de 18 places)<\/li>\n\n\n\n<li>Norv\u00e8ge (53e, en hausse de 15 places)<\/li>\n\n\n\n<li>R\u00e9publique tch\u00e8que (45e, en hausse de 12 places)<\/li>\n\n\n\n<li>France (49e, en hausse de 11 places)<\/li>\n\n\n\n<li>Slovaquie (40e, en hausse de 10 places)<\/li>\n<\/ul>\n\n\n\n<p>Le classement a \u00e9galement vu l&#8217;entr\u00e9e de cinq nouvelles \u00e9quipes, notamment l&#8217;Australie, qui est arriv\u00e9e \u00e0 la 59e place apr\u00e8s avoir r\u00e9alis\u00e9 un bilan invaincu lors de ses quatre premiers matches officiels lors des \u00e9liminatoires de la Coupe du Monde F\u00e9minine de la FIFA, Philippines 2025.<\/p>\n\n\n\n<p>Futsal Hommes : l&#8217;Arm\u00e9nie et la Pologne dans le top 3<\/p>\n\n\n\n<p>Le Br\u00e9sil continue de dominer le classement masculin, avec plus de 100 points d&#8217;avance sur le Portugal. La liste a \u00e9galement connu des changements significatifs, l&#8217;Espagne passant \u00e0 la troisi\u00e8me place, d\u00e9passant l&#8217;Argentine, tandis que l&#8217;Iran (cinqui\u00e8me) et le Maroc (sixi\u00e8me) progressent aux d\u00e9pens du Kazakhstan.<\/p>\n\n\n\n<p>Meilleurs candidats du classement :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Pologne (19e, en hausse de 3 places)<\/li>\n\n\n\n<li>Arm\u00e9nie (20e, en hausse de 11 places)<\/li>\n\n\n\n<li>Bosnie-Herz\u00e9govine (36e, en hausse de 12 places)<\/li>\n\n\n\n<li>Andorre (55e, en hausse de 13 places)<\/li>\n\n\n\n<li>Lettonie (60e, en hausse de 11 places)<\/li>\n\n\n\n<li>Gr\u00e8ce (88e, en hausse de 19 places)<\/li>\n<\/ul>\n\n\n\n<p>L&#8217;AFC a accueilli son plus grand nombre de matchs depuis la derni\u00e8re mise \u00e0 jour, l&#8217;Indon\u00e9sie en \u00e9tant le principal b\u00e9n\u00e9ficiaire, gagnant sept places pour atteindre la 21e place.<\/p>\n\n\n\n<p>Meilleures \u00e9quipes nationales par f\u00e9d\u00e9rations continentales<\/p>\n\n\n\n<p>Mesdames :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Am\u00e9rique du Sud : Br\u00e9sil (1\u00e8re place)<\/li>\n\n\n\n<li>Europe : Espagne (2e place)<\/li>\n\n\n\n<li>Asie : Tha\u00eflande (5e)<\/li>\n\n\n\n<li>CONCACAF : Costa Rica (26e)<\/li>\n\n\n\n<li>Oc\u00e9anie : Nouvelle-Z\u00e9lande (19e)<\/li>\n\n\n\n<li>Afrique : Maroc (47e)<\/li>\n<\/ul>\n\n\n\n<p>hommes:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Am\u00e9rique du Sud : Br\u00e9sil (1\u00e8re place)<\/li>\n\n\n\n<li>Europe : Portugal (2e place)<\/li>\n\n\n\n<li>Asie : Iran (5e place)<\/li>\n\n\n\n<li>CONCACAF : Costa Rica (32e)<\/li>\n\n\n\n<li>Oc\u00e9anie : Nouvelle-Z\u00e9lande (34e)<\/li>\n\n\n\n<li>Afrique : Maroc (6e place)<\/li>\n<\/ul>\n\n\n\n<p>Les fans de futsal peuvent s&#8217;attendre \u00e0 des comp\u00e9titions encore plus passionnantes, notamment avec la Coupe du monde f\u00e9minine qui d\u00e9butera aux Philippines en novembre prochain.<\/p>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>l\u2019\u00e9quipe news Vendredi 4 avril 2025 &#8211; 11h50 La FIFA a d\u00e9voil\u00e9 la premi\u00e8re \u00e9dition de son classement mondial de futsal pour 2025, avec plusieurs changements notables dans la liste apr\u00e8s que 183 matchs f\u00e9minins et 192 matchs masculins aient \u00e9t\u00e9 jou\u00e9s. Futsal f\u00e9minin : l&#8217;Australie entre en force au classement Le classement du futsal<\/p>","protected":false},"author":1,"featured_media":4225,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-4223","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-sport"},"_links":{"self":[{"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/posts\/4223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/comments?post=4223"}],"version-history":[{"count":2,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/posts\/4223\/revisions"}],"predecessor-version":[{"id":4226,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/posts\/4223\/revisions\/4226"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/media\/4225"}],"wp:attachment":[{"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/media?parent=4223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/categories?post=4223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/tags?post=4223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}