{"id":4200,"date":"2025-04-01T18:43:38","date_gmt":"2025-04-01T17:43:38","guid":{"rendered":"https:\/\/fr.lequipenews.ma\/?p=4200"},"modified":"2025-04-01T18:45:25","modified_gmt":"2025-04-01T17:45:25","slug":"4200-2","status":"publish","type":"post","link":"https:\/\/fr.lequipenews.ma\/fr\/4200-2\/","title":{"rendered":"Wolverhampton prolonge le contrat de Jo\u00e3o Gomes jusqu&#8217;en 2030"},"content":{"rendered":"<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">l\u2019\u00e9quipe news<\/mark><\/p>\n\n\n\n<p>Mardi 1er avril 2025 &#8211; 17h34<\/p>\n\n\n\n<p><strong>\u00c9crit par : A.T.<\/strong><\/p>\n\n\n\n<p>Wolverhampton Wanderers a annonc\u00e9 une prolongation de contrat de cinq ans pour le milieu de terrain br\u00e9silien Joao Gomes, le gardant au club jusqu&#8217;en 2030. Depuis son arriv\u00e9e en provenance de Flamengo il y a deux ans, Gomes a fait 80 apparitions et est devenu un pilier de l&#8217;effectif des Wolves, ce qui a incit\u00e9 le club \u00e0 obtenir sa prolongation<\/p>","protected":false},"excerpt":{"rendered":"<p>l\u2019\u00e9quipe news Mardi 1er avril 2025 &#8211; 17h34 \u00c9crit par : A.T. Wolverhampton Wanderers a annonc\u00e9 une prolongation de contrat de cinq ans pour le milieu de terrain br\u00e9silien Joao Gomes, le gardant au club jusqu&#8217;en 2030. Depuis son arriv\u00e9e en provenance de Flamengo il y a deux ans, Gomes a fait 80 apparitions et<\/p>","protected":false},"author":1,"featured_media":4203,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-4200","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-sport"},"_links":{"self":[{"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/posts\/4200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/comments?post=4200"}],"version-history":[{"count":3,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/posts\/4200\/revisions"}],"predecessor-version":[{"id":4204,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/posts\/4200\/revisions\/4204"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/media\/4203"}],"wp:attachment":[{"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/media?parent=4200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/categories?post=4200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/tags?post=4200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}