{"id":3825,"date":"2025-03-17T18:03:39","date_gmt":"2025-03-17T17:03:39","guid":{"rendered":"https:\/\/fr.lequipenews.ma\/?p=3825"},"modified":"2025-03-17T18:04:17","modified_gmt":"2025-03-17T17:04:17","slug":"3825-2","status":"publish","type":"post","link":"https:\/\/fr.lequipenews.ma\/fr\/3825-2\/","title":{"rendered":"Bach accepte l\u2019inclusion de la boxe aux Jeux Olympiques de Los Angeles 2028."},"content":{"rendered":"<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">L\u2019\u00c9quipe News<\/mark><\/p>\n\n\n\n<p>Lundi 17 mars 2025 &#8211; 16:28<\/p>\n\n\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">Par : Abdel Fattah Tkhim<\/mark><\/p>\n\n\n\n<p>Le pr\u00e9sident du Comit\u00e9 international olympique (CIO), Thomas Bach, a donn\u00e9 son feu vert lundi \u00e0 l\u2019inclusion de la boxe au programme des Jeux olympiques de Los Angeles 2028. Toutefois, cette d\u00e9cision doit encore \u00eatre soumise au vote de l\u2019Assembl\u00e9e g\u00e9n\u00e9rale en Gr\u00e8ce, pr\u00e9vu cette semaine, lors duquel un nouveau pr\u00e9sident du CIO sera \u00e9lu.<\/p>\n\n\n\n<p>Apr\u00e8s la r\u00e9union de la commission ex\u00e9cutive du CIO, Bach a confirm\u00e9 que \u00ab la seule d\u00e9cision prise est l\u2019ajout de la boxe au programme des Jeux de Los Angeles \u00bb. Il s\u2019est \u00e9galement dit \u00ab totalement confiant \u00bb quant \u00e0 l\u2019approbation de cette d\u00e9cision par l\u2019Assembl\u00e9e g\u00e9n\u00e9rale, d\u00e9clarant : \u00ab Les boxeurs du monde entier seront assur\u00e9s de leur participation aux Jeux olympiques de Los Angeles 2028 \u00bb.<\/p>\n\n\n\n<p>Cette d\u00e9cision intervient apr\u00e8s la reconnaissance provisoire, en f\u00e9vrier dernier, de l\u2019organisation mondiale de boxe \u00ab World Boxing \u00bb, qui sera d\u00e9sormais charg\u00e9e de superviser les comp\u00e9titions \u00e0 la place de la F\u00e9d\u00e9ration internationale de boxe (IBA), bannie par le CIO depuis 2019.<\/p>\n\n\n\n<p>Fond\u00e9e en 2023 apr\u00e8s plusieurs ann\u00e9es de conflits ayant affect\u00e9 la discipline, la nouvelle organisation regroupe aujourd\u2019hui 78 f\u00e9d\u00e9rations nationales, parmi lesquelles figurent les \u00c9tats-Unis, le Japon, la Grande-Bretagne, la France et l\u2019Allemagne, ainsi que seulement six f\u00e9d\u00e9rations africaines.<\/p>\n\n\n\n<p>Concernant les d\u00e9lais d\u2019adh\u00e9sion \u00e0 cette nouvelle organisation, Bach a pr\u00e9cis\u00e9 que cela \u00ab d\u00e9pendra des qualifications \u00bb, qui varient selon les pays et pourraient \u00eatre organis\u00e9es peu avant les Jeux olympiques.<\/p>\n\n\n\n<p>La boxe est l\u2019un des sports phares des Jeux olympiques modernes. Elle a fait sa premi\u00e8re apparition aux Jeux de 1904 et a \u00e9t\u00e9 pr\u00e9sente \u00e0 toutes les \u00e9ditions suivantes, \u00e0 l\u2019exception de celle de 1912. Cependant, ce sport a \u00e9t\u00e9 marqu\u00e9 par des tensions persistantes entre le CIO et la F\u00e9d\u00e9ration internationale de boxe, dirig\u00e9e par le Russe Umar Kremlev, un proche du Kremlin.<\/p>\n\n\n\n<p>La boxe n\u2019a \u00e9t\u00e9 incluse aux Jeux de Tokyo 2021 qu\u2019apr\u00e8s l\u2019intervention du CIO pour en assurer la gestion, une situation qui s\u2019est r\u00e9p\u00e9t\u00e9e pour Paris 2024, dans un contexte de tensions croissantes entre les deux parties et de suspension des activit\u00e9s de l\u2019IBA.<\/p>","protected":false},"excerpt":{"rendered":"<p>L\u2019\u00c9quipe News Lundi 17 mars 2025 &#8211; 16:28 Par : Abdel Fattah Tkhim Le pr\u00e9sident du Comit\u00e9 international olympique (CIO), Thomas Bach, a donn\u00e9 son feu vert lundi \u00e0 l\u2019inclusion de la boxe au programme des Jeux olympiques de Los Angeles 2028. Toutefois, cette d\u00e9cision doit encore \u00eatre soumise au vote de l\u2019Assembl\u00e9e g\u00e9n\u00e9rale en<\/p>","protected":false},"author":1,"featured_media":3826,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[6],"tags":[],"class_list":{"0":"post-3825","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-sport"},"_links":{"self":[{"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/posts\/3825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/comments?post=3825"}],"version-history":[{"count":3,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/posts\/3825\/revisions"}],"predecessor-version":[{"id":3829,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/posts\/3825\/revisions\/3829"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/media\/3826"}],"wp:attachment":[{"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/media?parent=3825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/categories?post=3825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/fr.lequipenews.ma\/fr\/wp-json\/wp\/v2\/tags?post=3825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}